{"id":8047,"date":"2026-04-09T20:11:23","date_gmt":"2026-04-09T17:11:23","guid":{"rendered":"https:\/\/residence-estate.ge\/?post_type=objects&#038;p=8047"},"modified":"2026-05-05T13:27:15","modified_gmt":"2026-05-05T10:27:15","slug":"a-laconic-studio-with-a-balcony-35-2-m%c2%b2-solana-grand-residence","status":"publish","type":"objects","link":"https:\/\/residence-estate.ge\/uk\/objects\/a-laconic-studio-with-a-balcony-35-2-m%c2%b2-solana-grand-residence\/","title":{"rendered":"\u041b\u0430\u043a\u043e\u043d\u0438\u0447\u043d\u0430\u044f \u0441\u0442\u0443\u0434\u0438\u044f \u0441 \u0431\u0430\u043b\u043a\u043e\u043d\u043e\u043c 35.2 \u043c\u00b2 \u0432"},"featured_media":8048,"parent":0,"template":"","objects-other":[234,242,233,230,231,232,228,229],"objects-readiness":[254],"objects-type":[179,180],"objects-city":[39,225],"objects-developers":[336],"objects-bathrooms":[63],"objects-bedrooms":[67],"class_list":["post-8047","objects","type-objects","status-publish","has-post-thumbnail","hentry","objects-other-terrace","objects-other-sea-view","objects-other-investments","objects-other-cheap","objects-other-from-developer","objects-other-pool","objects-other-black-sea","objects-other-elite","objects-readiness-254","objects-type-hotel-rooms","objects-type-flats","objects-city-batumi","objects-city-kobuleti","objects-developers-solana","objects-bathrooms-63","objects-bedrooms-studio"],"acf":[],"_links":{"self":[{"href":"https:\/\/residence-estate.ge\/uk\/wp-json\/wp\/v2\/objects\/8047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/residence-estate.ge\/uk\/wp-json\/wp\/v2\/objects"}],"about":[{"href":"https:\/\/residence-estate.ge\/uk\/wp-json\/wp\/v2\/types\/objects"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/residence-estate.ge\/uk\/wp-json\/wp\/v2\/media\/8048"}],"wp:attachment":[{"href":"https:\/\/residence-estate.ge\/uk\/wp-json\/wp\/v2\/media?parent=8047"}],"wp:term":[{"taxonomy":"objects-other","embeddable":true,"href":"https:\/\/residence-estate.ge\/uk\/wp-json\/wp\/v2\/objects-other?post=8047"},{"taxonomy":"objects-readiness","embeddable":true,"href":"https:\/\/residence-estate.ge\/uk\/wp-json\/wp\/v2\/objects-readiness?post=8047"},{"taxonomy":"objects-type","embeddable":true,"href":"https:\/\/residence-estate.ge\/uk\/wp-json\/wp\/v2\/objects-type?post=8047"},{"taxonomy":"objects-city","embeddable":true,"href":"https:\/\/residence-estate.ge\/uk\/wp-json\/wp\/v2\/objects-city?post=8047"},{"taxonomy":"objects-developers","embeddable":true,"href":"https:\/\/residence-estate.ge\/uk\/wp-json\/wp\/v2\/objects-developers?post=8047"},{"taxonomy":"objects-bathrooms","embeddable":true,"href":"https:\/\/residence-estate.ge\/uk\/wp-json\/wp\/v2\/objects-bathrooms?post=8047"},{"taxonomy":"objects-bedrooms","embeddable":true,"href":"https:\/\/residence-estate.ge\/uk\/wp-json\/wp\/v2\/objects-bedrooms?post=8047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}